{"id":732,"date":"2017-03-24T14:24:55","date_gmt":"2017-03-24T13:24:55","guid":{"rendered":"https:\/\/dollsanddolls.com\/blog\/?p=732"},"modified":"2023-06-12T15:59:09","modified_gmt":"2023-06-12T14:59:09","slug":"munecas-de-comunion","status":"publish","type":"post","link":"https:\/\/dollsanddolls.com\/blog\/munecas-de-comunion\/","title":{"rendered":"COMUNIONES Y LAS MU\u00d1ECAS DE COMUNI\u00d3N"},"content":{"rendered":"<p style=\"text-align: left;\">Dentro de unos meses llegar\u00e1 la tan esperada \u00e9poca de Comuniones en la cual los ni\u00f1os recibir\u00e1n su Primera Comuni\u00f3n llenos de emoci\u00f3n e ilusi\u00f3n. Ser\u00e1 un d\u00eda tan especial que lo recordar\u00e1n toda su vida. A lo largo del tiempo han ido variando los regalos de Comuni\u00f3n, pero lo que nunca ha dejado de estar son las <a href=\"https:\/\/dollsanddolls.com\/es\/munecas-de-comunion\" target=\"_blank\" rel=\"noopener noreferrer\">mu\u00f1ecas de Comuni\u00f3n<\/a>.<\/p>\n<p>A continuaci\u00f3n, vamos a contar una breve historia sobre esta tradici\u00f3n cat\u00f3lica: origen, tipos de ceremonias, tradiciones\u2026<\/p>\n<h2><strong>HISTORIA DE LA COMUNI\u00d3N<\/strong><\/h2>\n<p>La Primera Comuni\u00f3n es un acto ceremonial, conocido como el sacramento de la Eucarist\u00eda, relevante en la vida de los cat\u00f3licos. Es practicado por ni\u00f1os entre los siete y doce a\u00f1os, principalmente de forma colectiva y es oficiado por un sacerdote. Puede celebrarse en cualquier momento, aunque el d\u00eda por excelencia para su celebraci\u00f3n es el domingo en La Santa Misa.<\/p>\n<p>La eucarist\u00eda fue instaurada por Jesucristo en la \u00daltima Cena cuando tomando en sus manos el pan, lo parti\u00f3 y se lo dio a sus disc\u00edpulos diciendo: <em>\u00abEste es mi cuerpo que ser\u00e1 entregado por vosotros para el perd\u00f3n de los pecados. Tomad y bebed todos de \u00e9l porque esta es mi sangre, sangre de la alianza nueva y eterna que ser\u00e1 derramada por vosotros y por todos los hombres para el perd\u00f3n de los pecados. Haced esto en conmemoraci\u00f3n m\u00eda.\u00bb<\/em><\/p>\n<p>En esta ceremonia, los ni\u00f1os reciben a Cristo en la llamada Santa Misa o Sagrada Comuni\u00f3n. Los dos elementos esenciales de este rito son el Pan y el Vino como representaci\u00f3n del cuerpo de Cristo.<\/p>\n<p>En la Iglesia originaria, la Primera Comuni\u00f3n se recib\u00eda el mismo d\u00eda del bautismo. Esta costumbre desapareci\u00f3 en la Iglesia occidental hacia el siglo XII pero sigue perdurando hasta nuestros d\u00edas en la Iglesia oriental.<\/p>\n<figure id=\"attachment_733\" aria-describedby=\"caption-attachment-733\" style=\"width: 402px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"normal size-full wp-image-733\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-de-dos-ninos-tomando-la-comunion-en-valencia-en-1921.jpg\" alt=\"Foto de dos ni\u00f1os tomando la Comuni\u00f3n en 1921\" width=\"402\" height=\"640\" \/><figcaption id=\"caption-attachment-733\" class=\"wp-caption-text\">FOTO COMUNI\u00d3N A\u00d1O 1921<\/figcaption><\/figure>\n<p>Desde el siglo XII hasta el siglo XVII, la Primera Comuni\u00f3n pasaba desapercibida socialmente, se realizaban comuniones generales tanto de ni\u00f1os como de adultos en las principales fiestas eclesi\u00e1sticas. Tras la Contrarreforma (reforma cat\u00f3lica en respuesta a la reforma protestante de Mart\u00edn Lutero) la ceremonia se convirti\u00f3 en un acontecimiento relevante en la vida de las personas cat\u00f3licas, de car\u00e1cter p\u00fablico y de reuni\u00f3n familiar.<\/p>\n<p>En el siglo XVIII (1701 \u2013 1800) la Primera Comuni\u00f3n se celebraba a la edad de siete a\u00f1os y se fue elevando a los 10, 12 y 14 a\u00f1os. Hasta llegado el siglo XX exist\u00edan muchas divergencias de opini\u00f3n de cu\u00e1l era la edad id\u00f3nea para recibir la 1\u00aa Comuni\u00f3n.<\/p>\n<p>En 1910 (siglo XX), el Papa Pio X aprob\u00f3 el decreto Quann singulari que indicaba: \u201cNo hay edad uniforme y fija para realizar la Primera Comuni\u00f3n. Es un acto individual cuyo momento puede variar en cada ni\u00f1o. La Primera Comuni\u00f3n corresponde determinarla al confesor y a los padres (\u2026).\u201d<\/p>\n<p>Durante el siglo XIX (1801 \u2013 1900), la Primera Comuni\u00f3n se oficia una vez terminado el colegio pero sin celebrar la catequesis ya que lo habitual era que el p\u00e1rroco fuese a la escuela para impartirla o confirmar que el maestro lo hab\u00eda hecho.<\/p>\n<p>Durante el siglo XX (1901 \u2013 2000) la Primera Comuni\u00f3n, al igual que las bodas, se considera una ceremonia relevante en la vida de los cat\u00f3licos.<\/p>\n<p><img decoding=\"async\" class=\"normal aligncenter size-full wp-image-735\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-antigua-ninas-comunion-entre-1900-y-1926.jpg\" alt=\"Foto varias ni\u00f1as celebrando la Comuni\u00f3n entre 1906 y 1922\" width=\"640\" height=\"408\" \/><\/p>\n<p>Desde 1910 hasta 1970 aproximadamente, en las familias con un alto poder adquisitivo, la Primera Comuni\u00f3n se celebraba por todo lo alto convirti\u00e9ndose en un acto social. Las familias que no dispon\u00edan de un buen nivel econ\u00f3mico, realizaban la celebraci\u00f3n en sus casas con una merienda o en los colegios e instituciones con un desayuno como homenaje a los ni\u00f1os que iban a comulgar.<\/p>\n<figure id=\"attachment_734\" aria-describedby=\"caption-attachment-734\" style=\"width: 487px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"normal size-full wp-image-734\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-antigua-ninos-con-parroco.jpg\" alt=\"Foto de varios ni\u00f1os con el p\u00e1rroco para celebrar la Comuni\u00f3n en 1924\" width=\"487\" height=\"640\" \/><figcaption id=\"caption-attachment-734\" class=\"wp-caption-text\">FOTO COMUNI\u00d3N A\u00d1O 1924<\/figcaption><\/figure>\n<p>Posteriormente y hasta el d\u00eda de hoy, la 1\u00aa Comuni\u00f3n se convierte en una ocasi\u00f3n especial donde los protagonistas se sienten especiales con sus trajes por celebrar un d\u00eda tan emotivo en su vida.<\/p>\n<h2><strong>CEREMONIAS PRIMERA COMUNI\u00d3N<\/strong><\/h2>\n<p>Tanto la celebraci\u00f3n de la Primera Comuni\u00f3n como actos festivos que contin\u00faan a la misma, var\u00edan dependiendo de la cultura, las creencias, el nivel econ\u00f3mico, la tradici\u00f3n\u2026. Pero el prop\u00f3sito es en todos los casos el mismo: <em>\u201cLa Comuni\u00f3n entre la persona y el cuerpo y la sangre de Jesucristo\u201d.<\/em><\/p>\n<p>Algunas de las ceremonias religiosas que existen en la actualidad son:<\/p>\n<p><strong><em>Las ceremonias colectivas <\/em><\/strong>se celebran en grupo, principalmente en centros educativos religiosos y Parroquias donde se preparan para la ceremonia a trav\u00e9s de la catequesis que va subiendo de nivel a medida que avanza su contenido.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal aligncenter size-large wp-image-738\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-de-varios-ninos-y-ninas-haciendo-la-primera-comunion-1024x818.jpg\" alt=\"Foto varios ni\u00f1os tomando al primera Comuni\u00f3n en una Iglesia junto al p\u00e1rroco y sus catequistas\" width=\"1024\" height=\"818\" \/><\/p>\n<p>Seg\u00fan el catecismo de la Iglesia Cat\u00f3lica, la eucarist\u00eda representa un <em>\u201csigno de unidad, v\u00ednculo de caridad y banquete pascual en que se recibe a Cristo, el alma se llena de gracia y se nos da prenda de la vida eterna\u201d.<\/em><\/p>\n<p><strong><em>Las ceremonias colectivas uniformadas<\/em> <\/strong>suelen celebrase en familias con una buena posici\u00f3n econ\u00f3mica y exigen que todos los comulgantes utilicen el mismo traje o vestido sin ninguna variaci\u00f3n de color, dise\u00f1o o costura.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal aligncenter size-full wp-image-739\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-ceremonia-colectiva-uniformada.jpg\" alt=\"Foto de varios ni\u00f1os tomando la Primera Comuni\u00f3n en una ceremonia colectiva uniformada\" width=\"800\" height=\"988\" \/><\/p>\n<p><strong><em>La ceremonia individual<\/em><\/strong> se oficia de forma privada con un m\u00e1ximo de dos personas.<\/p>\n<p><strong><em>La ceremonia de mayor conciencia<\/em> <\/strong>se realiza cuando los infantes tienen quince o diecis\u00e9is a\u00f1os ya que son m\u00e1s conscientes de sus actos y pueden comprender mejor el significado del sacramento de la Primera Comuni\u00f3n y de la importancia y relevancia que tiene en la vida de una persona cat\u00f3lica.<\/p>\n<p><strong><em>Las ceremonias no convencionales<\/em><\/strong> son poco frecuentes e incluyen ceremonias como:<\/p>\n<ul>\n<li><em><strong>Ceremonia simb\u00f3lica simple<\/strong>:<\/em> donde no se utiliza ning\u00fan tipo de traje o vestido especial sino el vestuario del d\u00eda a d\u00eda.<\/li>\n<li><em><strong>Ceremonia de vestuario contempor\u00e1neo<\/strong>:<\/em> celebrada \u00fanicamente por ni\u00f1as que lucen un vestuario formal pero moderno compuesto entre otras cosas por minifalda, maquillaje y zapatos de tac\u00f3n.<\/li>\n<li><strong><em>Ceremonia domiciliaria<\/em>:<\/strong> Reservada para personas que no pueden asistir a la parroquia por lo que el sacerdote se desplaza hasta el domicilio para celebrar la Primera Comuni\u00f3n.<\/li>\n<\/ul>\n<h2><strong>INDUMENTARIA COMUNI\u00d3N<\/strong><\/h2>\n<p>Con el tiempo, al igual que ha pasado con la ceremonia, la indumentaria ha ido evolucionando y es diferente seg\u00fan el pa\u00eds, la cultura, el poder adquisitivo&#8230;<\/p>\n<p>En el mundo occidental, a partir del siglo XX (sobre 1910 aproximadamente), en las familias pudientes, el vestido de las ni\u00f1as se representa en color blanco, como s\u00edmbolo de pureza, acompa\u00f1ado por un velo en la cabeza que no les cubr\u00eda la cara. Los ni\u00f1os sol\u00edan llevar un traje gris o en tono oscuro sobre el cual se colocaba un brazalete blanco. Las personas que en esa \u00e9poca no iban al colegio realizaban la Comuni\u00f3n cuando iban a contraer matrimonio.<\/p>\n<figure id=\"attachment_740\" aria-describedby=\"caption-attachment-740\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"normal size-full wp-image-740\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-nina-comunion-ano-1920.jpg\" alt=\"Foto de una ni\u00f1a tomando la Primera Comuni\u00f3n en 1920\" width=\"310\" height=\"500\" \/><figcaption id=\"caption-attachment-740\" class=\"wp-caption-text\">FOTO COMUNI\u00d3N A\u00d1O 1920<\/figcaption><\/figure>\n<figure id=\"attachment_741\" aria-describedby=\"caption-attachment-741\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"normal wp-image-741\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-nina-comunion-ano-1945.jpg\" alt=\"Foto de una ni\u00f1a tomando la Primera Comuni\u00f3n en 1945\" width=\"310\" height=\"428\" \/><figcaption id=\"caption-attachment-741\" class=\"wp-caption-text\">FOTO COMUNI\u00d3N A\u00d1O 1945<\/figcaption><\/figure>\n<figure id=\"attachment_742\" aria-describedby=\"caption-attachment-742\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"normal wp-image-742\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-ninos-haciendo-la-comunion-en-1948-1-300x200.jpg\" alt=\"Foto de varios ni\u00f1os tomando la Primera Comuni\u00f3n en 1948\" width=\"400\" height=\"267\" \/><figcaption id=\"caption-attachment-742\" class=\"wp-caption-text\">FOTO COMUNI\u00d3N A\u00d1O 1948<\/figcaption><\/figure>\n<figure id=\"attachment_743\" aria-describedby=\"caption-attachment-743\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"normal wp-image-743\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-ninos-haciendo-la-comunion-en-1955-300x209.jpg\" alt=\"Foto de varios ni\u00f1os tomando la Primera Comuni\u00f3n en 1955\" width=\"400\" height=\"279\" \/><figcaption id=\"caption-attachment-743\" class=\"wp-caption-text\">FOTO COMUNI\u00d3N A\u00d1O 1955<\/figcaption><\/figure>\n<figure id=\"attachment_745\" aria-describedby=\"caption-attachment-745\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"normal wp-image-745\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-nina-comunion-a\u00f1os-60.jpg\" alt=\"Foto de una ni\u00f1a tomando la Primera Comuni\u00f3n en 1964\" width=\"310\" height=\"482\" \/><figcaption id=\"caption-attachment-745\" class=\"wp-caption-text\">FOTO COMUNI\u00d3N A\u00d1O 1964<\/figcaption><\/figure>\n<p>Adem\u00e1s de que los trajes de comuni\u00f3n sean de color blanco como s\u00edmbolo de pureza, es importante que los trajes y vestidos vayan acompa\u00f1ados de detalles como: unos guantes, un rosario, un misal (libro de oraciones) y una limosnera donde se guardan las monedas que familiares y amigos dan a los infantes cuando reparten los recordatorios o estampas de ese gran d\u00eda. Hay comulgantes que portan una vela de parafina en la mano que encienden durante la ceremonia para recordar la luz de Cristo.<\/p>\n<p>A d\u00eda de hoy la vestimenta de la Primera Comuni\u00f3n sigue la misma l\u00ednea que a\u00f1os anteriores pero con toques actuales, siendo los vestidos de las ni\u00f1as de color blanco o crema y utilizando todo tipo de accesorios que complementan con el vestido.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal alignleft size-medium wp-image-746\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-nina-con-vestido-comunion-actual-225x300.jpg\" alt=\"Foto ni\u00f1a vestida de Comuni\u00f3n con traje actual\" width=\"225\" height=\"300\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal alignright wp-image-747 size-medium\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-nina-con-vestido-comunion-actual-1-225x300.jpg\" alt=\"Foto ni\u00f1a vestida de Comuni\u00f3n con traje actual\" width=\"225\" height=\"300\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Los ni\u00f1os siguen luciendo trajes de marinero, aunque tambi\u00e9n se utilizan de almirante, de general\u2026. La explicaci\u00f3n de utilizar estos trajes puede estar relacionada con el origen del cristianismo ya que al parecer, los primeros disc\u00edpulos de Jes\u00fas fueron pescadores.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal aligncenter wp-image-749 size-full\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-de-varios-ninos-y-ninas-haciendo-la-comunion.jpg\" alt=\"Foto de varios ni\u00f1os tomando la Primera Comuni\u00f3n con vestimenta actual\" width=\"640\" height=\"439\" \/><\/p>\n<p>En la actualidad hay dise\u00f1adores que preparan colecciones espec\u00edficas de vestidos y trajes de Comuni\u00f3n. Hay todo tipo de dise\u00f1os con acabados preciosos, colecciones sencillas y elegantes, vestidos vaporosos o sencillos con ca\u00edda, con adornos en la cintura o fajines, acompa\u00f1ados de complementos como diademas o tocados. Un amplio abanico de vestidos y trajes que se van ampliando a\u00f1o tras a\u00f1o.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal aligncenter wp-image-750\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-coleccion-vestidos-comunion-rosa-clara.jpg\" alt=\"Foto ni\u00f1as vestidas de Comuni\u00f3n con vestidos de una colecci\u00f3n de Rosa Clara del a\u00f1o 2012\" width=\"1023\" height=\"400\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal aligncenter wp-image-751\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-traje-comunion-ninos-2016.jpg\" alt=\"Foto de varios ni\u00f1os vestidos con trajes de Primera Comuni\u00f3n procedentes de dise\u00f1adores\" width=\"652\" height=\"391\" \/><\/p>\n<h2><strong>TRADICIONES PRIMERA COMUNI\u00d3N<\/strong><\/h2>\n<p>Las tradiciones para ese d\u00eda son muchas y muy variadas, desde las invitaciones para repartir entre familiares, amigos y otros invitados hasta un libro de firmas donde los asistentes le dedicar\u00e1n unas cari\u00f1osas palabras.<\/p>\n<p>Como si de una boda se tratase, es muy com\u00fan repartir alg\u00fan detalle a los invitados donde aparece el nombre del comulgante junto con la fecha y lugar de celebraci\u00f3n as\u00ed como encargar a un profesional un reportaje fotogr\u00e1fico.<\/p>\n<p>En cuanto a los regalos, se ha pasado de los regalos tradicionales, biblias, rosarios\u2026a regalos m\u00e1s modernos como videojuegos, tel\u00e9fonos m\u00f3viles, tablets.<\/p>\n<p>Uno de los regalos imprescindibles que no puede faltar en un d\u00eda tan se\u00f1alado e irrepetible es una mu\u00f1eca de Comuni\u00f3n que se convertir\u00e1 en un recuerdo que perdurar\u00e1 en el tiempo.<\/p>\n<p style=\"text-align: center;\"><a target=\"_blank\" class=\"tw-button  custom blue large  shortcode\" href=\"https:\/\/dollsanddolls.com\/es\/munecas-de-comunion\" >REGALAR MU\u00d1ECA DE COMUNI\u00d3N<\/a>\n<h3><strong>TIPOS DE MU\u00d1ECAS DE COMUNI\u00d3N<\/strong><\/h3>\n<p>Las mu\u00f1ecas de Comuni\u00f3n tambi\u00e9n han variado con el paso de los a\u00f1os, pasando desde las mu\u00f1ecas de terracota (hechas con arcilla) hasta las actuales mu\u00f1ecas de vinilo.<\/p>\n<p><strong>MU\u00d1ECAS DE COMUNI\u00d3N DE TERRACOTA:<\/strong> Famosas en los a\u00f1os 30 y 40 del siglo XX gracias a su bajo coste. Su atuendo estaba compuesto por trajes inspirados en los vestidos de la \u00e9poca, acompa\u00f1ados por un velo, una limosnera y una medalla con s\u00edmbolo religioso.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal aligncenter wp-image-753 size-medium\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-muneca-terracota-anos-40-1-280x300.jpg\" alt=\"Foto mu\u00f1eca de Comuni\u00f3n hecha de Terracota en los a\u00f1os 40\" width=\"280\" height=\"300\" srcset=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-muneca-terracota-anos-40-1-280x300.jpg 280w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-muneca-terracota-anos-40-1-410x441.jpg 410w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-muneca-terracota-anos-40-1-525x564.jpg 525w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-muneca-terracota-anos-40-1.jpg 550w\" sizes=\"(max-width: 280px) 100vw, 280px\" \/><\/p>\n<p><strong>MU\u00d1ECAS CART\u00d3N-PIEDRA:<\/strong> Para realizar este tipo de mu\u00f1ecas, se utiliza una t\u00e9cnica similar al papel mach\u00e9, usando papel o cart\u00f3n y yeso o escayola. Las mu\u00f1ecas de Comuni\u00f3n realizadas en cart\u00f3n piedra fueron famosas a partir de 1940. Su cuerpo estaba fabricado en \u00e9ste material y algunas llevaban la cabeza de celuloide. Su vestimenta era similar a la que luc\u00edan las ni\u00f1as en la \u00e9poca e inclu\u00edan una cofia, una limosnera y un rosario.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal alignleft size-medium wp-image-754\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-muneca-morena-de-carton-piedra-anos-40-1-188x300.jpg\" alt=\"Foto mu\u00f1eca de Comuni\u00f3n de Cart\u00f3n Piedra a\u00f1os 40\" width=\"188\" height=\"300\" srcset=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-muneca-morena-de-carton-piedra-anos-40-1-188x300.jpg 188w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-muneca-morena-de-carton-piedra-anos-40-1.jpg 452w\" sizes=\"(max-width: 188px) 100vw, 188px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal alignright wp-image-755\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-muneca-carton-piedra-anos-40-50-1-197x300.jpg\" alt=\"Foto mu\u00f1eca de Comuni\u00f3n de Cart\u00f3n Piedra a\u00f1os 40-50\" width=\"197\" height=\"300\" srcset=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-muneca-carton-piedra-anos-40-50-1-197x300.jpg 197w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-muneca-carton-piedra-anos-40-50-1.jpg 475w\" sizes=\"(max-width: 197px) 100vw, 197px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En el a\u00f1o 1944 ya se comercializaba el famoso hermano de Mariquita P\u00e9rez. Juan\u00edn P\u00e9rez vestido de Primera Comuni\u00f3n, fabricado con el mismo material y con un traje blanco con una cadenita y un rosario<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal aligncenter size-full wp-image-756\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-muneco-juanin-perez-carton-piedra-comunion-ano-1944.jpg\" alt=\"Mu\u00f1eco Juan\u00edn P\u00e9rez Comuni\u00f3n a\u00f1o 1944\" width=\"199\" height=\"300\" \/><\/p>\n<p><strong>MU\u00d1ECAS DE PORCELANA<\/strong>: Las mu\u00f1ecas de Comuni\u00f3n elaboradas en porcelana se empezaron a comercializar sobre la mitad del siglo XIX. Su ropa iba acorde a la \u00e9poca, que se completaba con pololos, can-can y accesorios con motivos religiosos como un rosario o una medallita con una virgen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal aligncenter size-full wp-image-757\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-muneca-de-porcelana-espanola-1.jpg\" alt=\"Mu\u00f1eca de Comuni\u00f3n hecha de porcelana\" width=\"398\" height=\"540\" srcset=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-muneca-de-porcelana-espanola-1.jpg 398w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-muneca-de-porcelana-espanola-1-221x300.jpg 221w\" sizes=\"(max-width: 398px) 100vw, 398px\" \/><\/p>\n<p><strong>MU\u00d1ECA DE VINILO: <\/strong>A partir de los a\u00f1os 60 del siglo XX se empezaron a fabricar y comercializar las mu\u00f1ecas de vinilo siendo un aut\u00e9ntico \u00e9xito ya que algunas inclu\u00edan una caja de sonido en el interior y ten\u00edan articulaciones en brazos y piernas. Una d\u00e9cada despu\u00e9s, se empieza a comercializar las mu\u00f1ecas de Comuni\u00f3n de vinilo, revolucionando el mercado y convirti\u00e9ndose en un \u00e9xito, como ocurri\u00f3 con las mu\u00f1ecas Nancy de Famosa <a href=\"https:\/\/dollsanddolls.com\/blog\/nancy-coleccion\/\" target=\"_blank\" rel=\"noopener noreferrer\">(clica aqu\u00ed s\u00ed quieres conocer m\u00e1s sobre la historia y reediciones de Nancy)<\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal aligncenter size-full wp-image-758\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-nancy-comunion-1970-1.jpg\" alt=\"Foto mu\u00f1eca de Comuni\u00f3n Nancy a\u00f1o 1970\" width=\"292\" height=\"440\" srcset=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-nancy-comunion-1970-1.jpg 292w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-nancy-comunion-1970-1-199x300.jpg 199w\" sizes=\"(max-width: 292px) 100vw, 292px\" \/><\/p>\n<h3><strong>LAS MU\u00d1ECAS DE COMUNI\u00d3N HOY EN D\u00cdA<\/strong><\/h3>\n<p>Actualmente, casi todos los fabricantes de mu\u00f1ecas comercializan mu\u00f1ecas de Comuni\u00f3n realizadas en vinilo, aportando cada marca su toque particular. Diferentes alturas y estilos y con vestidos de distinto dise\u00f1o pero siempre respetando el estilo cl\u00e1sico del traje de Comuni\u00f3n.<\/p>\n<p><a href=\"https:\/\/dollsanddolls.com\/es\/\" target=\"_blank\" rel=\"noopener noreferrer\">(Clica aqu\u00ed para ver y comprar las mu\u00f1ecas que tenemos de Comuni\u00f3n en nuestra tienda).<\/a><\/p>\n<p>Os mostramos algunos modelos actuales de mu\u00f1ecas de Comuni\u00f3n:<\/p>\n<h4><strong>Nancy Comuni\u00f3n de Famosa<\/strong><\/h4>\n<p>Nancy luce un cl\u00e1sico pero elegante vestido de color blanco con falda adornada por tres lorzas en la parte inferior y un bonito lazo con tres flores en la cintura. Acompa\u00f1a su vestido con una cinta con un lacito que decora su pelo, una limosnera, unos pendientes en forma de perla en tono dorado y una cadena con una cruz tambi\u00e9n en color dorado.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal aligncenter wp-image-759 size-medium\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-nancy-comunion-morena-2014-foto-completa-700011490-300x300.jpg\" alt=\"Foto mu\u00f1eca Nancy Comuni\u00f3n Morena\" width=\"300\" height=\"300\" srcset=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-nancy-comunion-morena-2014-foto-completa-700011490-300x300.jpg 300w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-nancy-comunion-morena-2014-foto-completa-700011490-150x150.jpg 150w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-nancy-comunion-morena-2014-foto-completa-700011490-75x75.jpg 75w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-nancy-comunion-morena-2014-foto-completa-700011490-740x740.jpg 740w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-nancy-comunion-morena-2014-foto-completa-700011490.jpg 750w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal aligncenter wp-image-760 size-medium\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-nancy-comunion-rubia-foto-completa-1011287-300x300.jpg\" alt=\"Foto mu\u00f1eca Nancy Comuni\u00f3n Rubia\" width=\"300\" height=\"300\" srcset=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-nancy-comunion-rubia-foto-completa-1011287-300x300.jpg 300w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-nancy-comunion-rubia-foto-completa-1011287-150x150.jpg 150w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-nancy-comunion-rubia-foto-completa-1011287-75x75.jpg 75w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-nancy-comunion-rubia-foto-completa-1011287-740x740.jpg 740w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-nancy-comunion-rubia-foto-completa-1011287.jpg 750w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Bella Comuni\u00f3n de Antonio Juan<\/strong><\/h4>\n<p>Mu\u00f1ecas con una altura de 45 cent\u00edmetros que lucen unos preciosos vestidos blancos acompa\u00f1ados por una diadema, unos pendientes, una medallita dorada y la cl\u00e1sica limosnera que no puede faltar ese d\u00eda tan especial.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal aligncenter size-medium wp-image-762\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-antonio-juan-bella-comunion-rubia-foto-completa-facebook-2801-300x300.jpg\" alt=\"Foto mu\u00f1eca de Comuni\u00f3n Bella Rubia de Antonio Juan\" width=\"300\" height=\"300\" srcset=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-antonio-juan-bella-comunion-rubia-foto-completa-facebook-2801-300x300.jpg 300w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-antonio-juan-bella-comunion-rubia-foto-completa-facebook-2801-150x150.jpg 150w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-antonio-juan-bella-comunion-rubia-foto-completa-facebook-2801-75x75.jpg 75w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-antonio-juan-bella-comunion-rubia-foto-completa-facebook-2801.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal aligncenter size-medium wp-image-761\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-antonio-juan-bella-comunion-morena-foto-completa-facebook-2801-300x300.jpg\" alt=\"Foto mu\u00f1eca de Comuni\u00f3n Bella Morena de Antonio Juan\" width=\"300\" height=\"300\" srcset=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-antonio-juan-bella-comunion-morena-foto-completa-facebook-2801-300x300.jpg 300w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-antonio-juan-bella-comunion-morena-foto-completa-facebook-2801-150x150.jpg 150w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-antonio-juan-bella-comunion-morena-foto-completa-facebook-2801-75x75.jpg 75w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-antonio-juan-bella-comunion-morena-foto-completa-facebook-2801.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h4><strong>Mu\u00f1ecas de Comuni\u00f3n Paola Reina<\/strong><\/h4>\n<p>La marca de mu\u00f1ecas Paola Reina tiene un amplio surtido de mu\u00f1ecas para celebrar ese d\u00eda tan especial. Mu\u00f1ecas de 32 cent\u00edmetros de alto como son Las Amigas hasta mu\u00f1ecas de 60 cent\u00edmetros como Las Reinas, que tienen m\u00e1s articulaciones que el resto de mu\u00f1ecas, lo que permitir\u00e1 hacer las delicias de las ni\u00f1as coloc\u00e1ndolas en la posici\u00f3n que prefieran.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal aligncenter size-medium wp-image-763\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-paola-reina-las-amigas-comunion-luis-claire-carol-foto-facebook-04820-04821-04822-300x300.jpg\" alt=\"Foto mu\u00f1ecas de Comuni\u00f3n de Paola Reina\" width=\"300\" height=\"300\" srcset=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-paola-reina-las-amigas-comunion-luis-claire-carol-foto-facebook-04820-04821-04822-300x300.jpg 300w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-paola-reina-las-amigas-comunion-luis-claire-carol-foto-facebook-04820-04821-04822-150x150.jpg 150w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-paola-reina-las-amigas-comunion-luis-claire-carol-foto-facebook-04820-04821-04822-75x75.jpg 75w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-paola-reina-las-amigas-comunion-luis-claire-carol-foto-facebook-04820-04821-04822.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h4><strong>Mu\u00f1ecas de Comuni\u00f3n Mariquita P\u00e9rez<\/strong><\/h4>\n<p>Mariquita P\u00e9rez sac\u00f3 al mercado el primer traje de Comuni\u00f3n con todos sus complementos en el primer cat\u00e1logo de la mu\u00f1eca (a\u00f1o 1941-1942) con el nombre de Azucena. Actualmente, Mariquita P\u00e9rez sigue comercializando mu\u00f1ecas vestidas de Comuni\u00f3n como lo son estas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal aligncenter size-medium wp-image-764\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-mariquita-perez-muneca-comunion-beig-foto-completa-facebook-MP50205-300x300.jpg\" alt=\"Mu\u00f1eca de Comuni\u00f3n de Mariquita P\u00e9rez\" width=\"300\" height=\"300\" srcset=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-mariquita-perez-muneca-comunion-beig-foto-completa-facebook-MP50205-300x300.jpg 300w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-mariquita-perez-muneca-comunion-beig-foto-completa-facebook-MP50205-150x150.jpg 150w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-mariquita-perez-muneca-comunion-beig-foto-completa-facebook-MP50205-75x75.jpg 75w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-mariquita-perez-muneca-comunion-beig-foto-completa-facebook-MP50205.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal aligncenter size-medium wp-image-765\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-mariquita-perez-muneca-comunion-blanca-foto-completa-facebook-MP50206-300x300.jpg\" alt=\"Mu\u00f1eca de Comuni\u00f3n de Mariquita P\u00e9rez\" width=\"300\" height=\"300\" srcset=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-mariquita-perez-muneca-comunion-blanca-foto-completa-facebook-MP50206-300x300.jpg 300w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-mariquita-perez-muneca-comunion-blanca-foto-completa-facebook-MP50206-150x150.jpg 150w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-mariquita-perez-muneca-comunion-blanca-foto-completa-facebook-MP50206-75x75.jpg 75w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-mariquita-perez-muneca-comunion-blanca-foto-completa-facebook-MP50206.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"normal aligncenter size-medium wp-image-766\" src=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-mariquita-perez-muneca-comunion-foto-completa-facebook-MP50148-300x300.jpg\" alt=\"Mu\u00f1eca de Comuni\u00f3n de Mariquita P\u00e9rez\" width=\"300\" height=\"300\" srcset=\"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-mariquita-perez-muneca-comunion-foto-completa-facebook-MP50148-300x300.jpg 300w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-mariquita-perez-muneca-comunion-foto-completa-facebook-MP50148-150x150.jpg 150w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-mariquita-perez-muneca-comunion-foto-completa-facebook-MP50148-75x75.jpg 75w, https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-mariquita-perez-muneca-comunion-foto-completa-facebook-MP50148.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Mariquita P\u00e9rez a pesar de los a\u00f1os, sigue manteniendo su cuidadoso dise\u00f1o, sus detallados conjuntos y sus accesorios y complementos que hacen que sea una mu\u00f1eca ideal para celebrar los d\u00edas m\u00e1s importantes de las ya no tan peque\u00f1as de la casa.<\/p>\n<p>\u00a1Regala ilusi\u00f3n y alegr\u00eda en un d\u00eda tan especial!<\/p>\n<pre>En nuestra web encontrar\u00e1s un amplio surtido de mu\u00f1ecas de Comuni\u00f3n de primera calidad y de distintas marcas. <a href=\"https:\/\/dollsanddolls.com\/es\/catalogsearch\/result\/?q=comuni%C3%B3n\" target=\"_blank\" rel=\"noopener noreferrer\">Clica aqu\u00ed para ver todos los productos que tenemos en stock. <\/a><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Dentro de unos meses llegar\u00e1 la tan esperada \u00e9poca de Comuniones en la cual los ni\u00f1os recibir\u00e1n su Primera Comuni\u00f3n llenos de emoci\u00f3n e ilusi\u00f3n. Ser\u00e1 un d\u00eda tan especial que lo recordar\u00e1n toda su vida. A lo largo del tiempo han ido variando los regalos de Comuni\u00f3n, pero lo que nunca ha dejado de&hellip;&nbsp;<a href=\"https:\/\/dollsanddolls.com\/blog\/munecas-de-comunion\/\" class=\"\" rel=\"bookmark\">Leer m\u00e1s &raquo;<span class=\"screen-reader-text\">COMUNIONES Y LAS MU\u00d1ECAS DE COMUNI\u00d3N<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":780,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[7,466],"tags":[114,115,116],"class_list":["post-732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia","category-munecas-maniquis","tag-comunion","tag-munecas-de-comunion","tag-primera-comunion"],"jetpack_featured_media_url":"https:\/\/dollsanddolls.com\/blog\/wp-content\/uploads\/2017\/03\/dolls-and-dolls-blog-munecas-de-comunion-foto-portada-4.jpg","_links":{"self":[{"href":"https:\/\/dollsanddolls.com\/blog\/wp-json\/wp\/v2\/posts\/732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dollsanddolls.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dollsanddolls.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dollsanddolls.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dollsanddolls.com\/blog\/wp-json\/wp\/v2\/comments?post=732"}],"version-history":[{"count":20,"href":"https:\/\/dollsanddolls.com\/blog\/wp-json\/wp\/v2\/posts\/732\/revisions"}],"predecessor-version":[{"id":3607,"href":"https:\/\/dollsanddolls.com\/blog\/wp-json\/wp\/v2\/posts\/732\/revisions\/3607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dollsanddolls.com\/blog\/wp-json\/wp\/v2\/media\/780"}],"wp:attachment":[{"href":"https:\/\/dollsanddolls.com\/blog\/wp-json\/wp\/v2\/media?parent=732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dollsanddolls.com\/blog\/wp-json\/wp\/v2\/categories?post=732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dollsanddolls.com\/blog\/wp-json\/wp\/v2\/tags?post=732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}